{"id":5376,"date":"2021-09-26T07:46:45","date_gmt":"2021-09-26T05:46:45","guid":{"rendered":"https:\/\/www.gerojenner.com\/wp\/?p=5376"},"modified":"2022-04-18T16:45:19","modified_gmt":"2022-04-18T14:45:19","slug":"hohlspiegel","status":"publish","type":"post","link":"https:\/\/www.gerojenner.com\/wp\/hohlspiegel\/","title":{"rendered":"Hohlspiegel"},"content":{"rendered":"\n<p><strong>Mahnruf eines nicht ganz unbekannten \u00f6sterreichischen K\u00fcnstlers, der sich an die Weisheiten der Hopi-Indianer h\u00e4lt.<!--more--><\/strong><\/p>\n\n\n\n<p>Lieber Gero,<\/p>\n\n\n\n<p>&#8230; Dem Wirklichkeitsbegriff der Main-Stream-Berichterstattung habe ich l\u00e4ngst abgeschworen und wundere mich immer mehr, wie jemand (damit bin ich G. J. gemeint) eine Pharma-Impf-Diktatur als L\u00f6sung dieser &#8222;Plan-demie&#8220; guthei\u00dfen kann. Wer immer noch glaubt, da\u00df es hier um den Schutz unserer Gesundheit geht, der hat wohl noch nie etwas von Klaus Schwab und seinem &#8222;Great Reset&#8220; geh\u00f6rt, oder von der &#8222;Agenda 21&#8220;. \/Das sind\/ Umerziehungsprogramme, die an die \/der\/ Substanz unserer Demokratischen Freiheits- und Unversehrtheisgesetze r\u00fctteln und&nbsp;dies scheint erst der Anfang einer transhumanen Horrorvision zu sein &#8230; Ich halte mich also mehr an die Hopi-Indianer \u2026<\/p>\n\n\n\n<p>Lieber Manfred,<\/p>\n\n\n\n<p>Ich bewundere Dich als gro\u00dfen Kenner Japans, und so darf ich wohl bekennen, dass Du mir mit den obigen Zeilen ein Satori-Erlebnis der besonderen Art bescherst: eine Erleuchtung, die mich schlagartig \u00fcber meine bisherige Naivit\u00e4t aufkl\u00e4rt. Ja, ich habe es zugelassen, dass man meine Freiheit und Unversehrtheit besch\u00e4digt. Wie so viele andere auch habe ich mich als Kind (wir tragen ja alle die Narben am Arm) ohne Widerspruch gegen die Pocken (und andere Krankheiten) impfen lassen statt lustvoll an dieser und anderen Seuchen zu krepieren und meinen Mitmenschen das hohe eigene Freiheitsbewusstsein zus\u00e4tzlich dadurch zu demonstrieren, dass ich mich f\u00fcr sie in einen Ansteckungsherd verwandle und sie gleichfalls lustvoll krepieren lasse. Du hat recht, die eigene Freiheit muss \u00fcber alles gehen!<\/p>\n\n\n\n<p>Ja, Du wirst es kaum glauben, aber so dumm bin ich damals gewesen. Die Impfungen vor meinen Reisen nach Indien habe ich sogar freiwillig gesucht, ohne vorher bei Klaus Schwab und den Hopi-Indianern nachzufragen. Die h\u00e4tten mich doch sicher dar\u00fcber aufgekl\u00e4rt, dass ich mich in meiner Dummheit allein den Interessen der Pharmaindustrie unterwerfe.<\/p>\n\n\n\n<p>Aber so war es eben: in meiner Naivit\u00e4t habe ich der Medizin und den Epidemiologen geglaubt &#8211; den Fachleuten also. Dabei h\u00e4tte ich wissen m\u00fcssen, dass K\u00fcnstler, Hopi-Indianer und vor allem Du eine Wesensschau betreiben, die unendlich viel tiefer reicht.<\/p>\n\n\n\n<p>Wei\u00dft Du, da kommt mir sogar eine Idee. Du k\u00f6nntest den Freiheitsbegriff noch wesentlich vertiefen, indem Du ihn auf den Lieben Gott beziehst. Dann h\u00e4ttest Du nicht nur das Wissen der Epidemiologen sondern auch noch das der fortschrittlichen Theologen in Frage gestellt.<\/p>\n\n\n\n<p>Der liebe Gott, so k\u00f6nntest Du etwa sagen, hat uns doch Krankheiten und Seuchen mit Bedacht und bester Absicht geschickt, damit wir die Chance haben, fr\u00fcher zu ihm ins Paradies zu gelangen! Darf die Medizin sich erlauben, SEINE Freiheit zu beschneiden, indem sie mit ihren Impfstoffen und Medikamenten willk\u00fcrlich in sein Werk eingreift?<\/p>\n\n\n\n<p>Du siehst, lieber Manfred. Nun bin ich doch endlich im Begriff \u2013 zugegeben: mit ziemlicher Versp\u00e4tung -, eigenst\u00e4ndig zu denken und mich an den Weisheiten der Hopis, von Klaus Schwab und nicht zuletzt Deiner Person zu orientieren. Wohin mich das wohl noch f\u00fchren wird?<\/p>\n\n\n\n<p>Dr. med. <strong>Kay Rohmann<\/strong> aus D\u00fcsseldorf schickt mir folge Mail:<\/p>\n\n\n\n<p>Sehr geehrter Herr Jenner,<br>Ihre Replik demonstriert eindrucksvoll die Angst vor den unabwendbaren Grundverf\u00fcgbarkeiten des Menschen, n\u00e4mlich Krankheit und Tod. Aber auch die Unterwerfung unter das Diktat einer politisch instrumentalisierten Wissenschaft, hier Medizin. \u00dcbrigens nach Verwendung der Pest als Waffe zur Erst\u00fcrmung belagerter St\u00e4dte und eventueller Brunnenvergiftungen mit Kadavern ein in der Neuzeit bislang nicht eingesetztes Instrument zur Gestaltung einer Gesellschaft. Sie sind doch ein intelligenter Mensch, was Sie in Ihren vielf\u00e4ltigen Aufs\u00e4tzen unter Beweis gestellt haben. Sie m\u00fcssten doch zumindest annehmen k\u00f6nnen, dass das menschliche, evolutionsbedingt perfektionierte Immunsystem bislang auf jedes Virus dergestalt reagiert hat, dass es dies letztendlich \u00fcberwunden hat. Ebenso werden Sie einr\u00e4umen k\u00f6nnen, dass Multimorbidit\u00e4t, sei sie demographisch oder zivilisationsbedingt, die unbestrittene Voraussetzung war, an einem viralen Infektgeschehen zu versterben.&nbsp;Vielleicht sind Sie in Unkenntnis dar\u00fcber, dass es bislang keine effektive antivirale Therapie gibt. Denken Sie nur an HIV, an dessen Therapie seit Jahrzehnten erfolglos geforscht wird.Sich jetzt der kollektiven Erwartung zu unterwerfen, dass neuartige Impfstoffe, die keinerlei Langzeitbeobachtungen nachweisen k\u00f6nnen, die Heilsbringers Exitstrategie seien, ist naiv und beweist einmal mehr: die Kluft zwischen menschlicher Existenz und nicht beeinflussbaren Verf\u00fcgbarkeiten l\u00e4sst sich nur durch Glauben \u00fcberbr\u00fccken.<br>Mit einem freundlichen Gru\u00df, Kay Rohmann<\/p>\n\n\n\n<p>Meine Antwort:<\/p>\n\n\n\n<p>Ja, ja, ich bin doch ein intelligenter Mensch, aber leider eben doch nicht intelligent genug. Aber im Ernst: Herrn Rohmann ist ein Hals-Nasen-Ohrenarzt, kein Epidemiologe. Wie wir alle ist also auch er auf die Aussagen der Fachleute angewiesen. Wenn weltweit 95 Prozent der Experten sich unmissverst\u00e4ndlich f\u00fcr das Impfen erkl\u00e4ren und die Statistik in s\u00e4mtlichen L\u00e4ndern ebenso unmissverst\u00e4ndlich beweist, dass \u00fcberall wo geimpft wird, nur ein Bruchteil der Menschen sterben, dann ist damit jede weitere Diskussion \u00fcberfl\u00fcssig. Dass nahezu alle Medikamente \u2013 auch Impfstoffe &#8211; nie einen absoluten Schutz bieten und manchmal auch unerfreuliche Nebenwirkungen haben, ist eine Binsenwahrheit. Worauf es ankommt, ist der Saldo. Wenn viel mehr Leben durch sie gerettet werden, also ohne ihre Anwendung verloren gehen, ist das ein ausreichendes Argument, dem sich kein Laie verschlie\u00dfen darf.<\/p>\n\n\n\n<p>Pfarrer Gerhard Lotete meldet sich mit folgenden Worten:<\/p>\n\n\n\n<p>Lieber Gero ! Ich glaube&nbsp; Dich richtig verstanden zu haben, wenn auch bei einigen Irritationen auftreten k\u00f6nn(t)en. Das betrifft die Hopi- Indiander- Aussagen. Augenscheinlich benutzt sie Dein Gegenpart als Hinweis darauf: man k\u00f6nne sich statt wissenschftlicher Beweise eher den spiritistischen Instiutionen einer Urbev\u00f6llkerung anvertrauen. Soweit so gut, aber es l\u00f6st bei manchen auch die Vision einer Verunglimpfung einer V\u00f6lkergruppe aus. Das m\u00fcsse doch nicht sein.<\/p>\n\n\n\n<p>Soweit dazu, was ich da h\u00f6re. Es bringt jedoch nicht Dein Anliegen in Verruf, den gesunden Menschenverstand und die historischen Belange zu untersch\u00e4tzen.<\/p>\n\n\n\n<p>Gru\u00df Gerhard<\/p>\n\n\n\n<p>Lieber Gerhard,<\/p>\n\n\n\n<p>ich habe mein Leben mit dem Studium fremder Kulturen (Indien, China, Japan) verbracht. Nicht l\u00e4ge mir ferner, nichts w\u00fcrde mir als gr\u00f6\u00dfere Dummheit erscheinen, als eine Verunglimpfung. Nat\u00fcrlich habe ich die ber\u00fchmte Studie der amerikanischen Ethnologin Ruth Benedict \u00fcber die Zunis gelesen. Aber wie Du richtig siehst, bin ich gegen hochtrabende Schwafelei allergisch.<\/p>\n\n\n\n<p><strong>Bruno Kathollnig<\/strong>, Dichter und Denker schickt mir folgende Zeilen:<\/p>\n\n\n\n<p>Sehr geehrter Herr Jenner!<\/p>\n\n\n\n<p>Herrlich, Ihre Antwort!<\/p>\n\n\n\n<p>Fast schon Poesie, welche den Nagel auf den Kopf tr\u00e4fe, w\u00e4re da nicht esoterische Kopflosigkeit im Spiel!<\/p>\n\n\n\n<p>Alles Gute!<\/p>\n\n\n\n<p>Bruno Kathollnig<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mahnruf eines nicht ganz unbekannten \u00f6sterreichischen K\u00fcnstlers, der sich an die Weisheiten der Hopi-Indianer h\u00e4lt.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5376","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/posts\/5376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/comments?post=5376"}],"version-history":[{"count":0,"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/posts\/5376\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/media?parent=5376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/categories?post=5376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gerojenner.com\/wp\/wp-json\/wp\/v2\/tags?post=5376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}